{"id":18954,"date":"2026-05-20T07:25:52","date_gmt":"2026-05-20T07:25:52","guid":{"rendered":"https:\/\/vapeuni.com\/?post_type=product&#038;p=18954"},"modified":"2026-05-22T09:12:47","modified_gmt":"2026-05-22T09:12:47","slug":"vhill-triple-90k-disposable-vape-90000-puffs","status":"publish","type":"product","link":"https:\/\/vapeuni.com\/fr\/produit\/vhill-triple-90k-disposable-vape-90000-puffs\/","title":{"rendered":"Vhill Triple 90000 Puff 3in1 90K Disposable Vape Switch Three Flavors"},"content":{"rendered":"<div data-page-id=\"OcbudiYCXod0l0xvq92cSVw6nqf\" data-lark-html-role=\"root\" data-docx-has-block-data=\"true\">\n<h1 class=\"ace-line ace-line old-record-id-OcbudiYCXod0l0xvq92cSVw6nqf\">VHILL Triple 90K 90000 Puffs Disposable Vape<\/h1>\n<div class=\"ace-line ace-line old-record-id-TvPhfF2PCdAq2qclKR4cNqWwnmd\">100% Original Factory China Wholesale VHILL Triple 90K Disposable Vape, an innovative big puff e-cigarette with 90000 puffs, combines high performance and stylish design, ideal for wholesale partners and vapers.<\/div>\n<div class=\"ace-line ace-line old-record-id-QJEzf9JIedfrPpcHKzvcmga6nnd\">Key Features: Rechargeable 850mAh battery (Type-C charging), smart display, 2%\/5% Nic Salt, 50ML e-liquid, Mesh Coils for smooth vapor, unique RGB light (color changes with battery and flavor) and quicksand appearance. Sensor start, disposable design, logo customizable.<\/div>\n<div class=\"ace-line ace-line old-record-id-GS98fOU52dZu5Lckwtycc2LRnhc\">11 Flavor Combinations:<\/div>\n<ol class=\"list-number1\" start=\"1\">\n<li class=\"ace-line ace-line old-record-id-BGXMfB6QIdsKEycuvAicnlB6nwg\" data-list=\"number\">\n<div>Strawberry Watermelon &amp; Lemon Lime &amp; Blueberry Coconut<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-IYhjfXetld6URocWmDcc6e4Snsf\" data-list=\"number\">\n<div>Blueberry Ice &amp; Fizz Cherry &amp; Raspberry Lemon<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-FgmNfCQqsdsz2xcSOHdc8HFDnAg\" data-list=\"number\">\n<div>Strawberry Kiwi &amp; Strawberry Vanilla Coke &amp; Mixed Berry<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-JerLfNQJPd0E8dc48Q2cs48snkb\" data-list=\"number\">\n<div>Strawberry Dragon Fruit &amp; Red Bull &amp; Raspberry Watermelon<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-VNGMfZhm6dKI5OcpOsec5fqMn6f\" data-list=\"number\">\n<div>Pineapple Coconut &amp; Mixed Fruit &amp; Blue Razz<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-CByyf480jdaUL5cVZjBcqvF0noe\" data-list=\"number\">\n<div>Blueberry Ice &amp; Black Dragon Ice &amp; Cherry Cola Ice<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-EwDkfl8n2deZiuc2Z24cICicnzg\" data-list=\"number\">\n<div>Peach Ice &amp; Pineapple Mango Peach &amp; Cranberry Lemon<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-GDdAffQ3vdFVbucn1CkcqgJYnOe\" data-list=\"number\">\n<div>Grape Ice &amp; Strawberry Candy &amp; Strawberry Raspberry Cherry<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-IRKSfgPK3dK6E5chm1vcZ3Vynrb\" data-list=\"number\">\n<div>Strawberry Banana &amp; Pineapple Coconut Ice &amp; Mango Ice<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-AEQYf1EyKdFloVchhEHclrSUnMb\" data-list=\"number\">\n<div>Blueberry Raspberry Ice &amp; Blueberry Cotton Candy &amp; Double Apple Ice<\/div>\n<\/li>\n<li class=\"ace-line ace-line old-record-id-Ukz6fpMyRdDsqbcofxKcRjMPnIg\" data-list=\"number\">\n<div>Strawberry Raspberry &amp; Triple Melon &amp; Sour Mango Pineapple<\/div>\n<\/li>\n<\/ol>\n<div class=\"ace-line ace-line old-record-id-EzrkfP0rsdOybGcHtLfcxcCmnnb\">Product Parameters:<\/div>\n<div>\n<table class=\"ace-table\" style=\"height: 139px;\" width=\"1293\" data-ace-table-col-widths=\"200;200;200;200\">\n<colgroup>\n<col width=\"200\" \/>\n<col width=\"200\" \/>\n<col width=\"200\" \/>\n<col width=\"200\" \/><\/colgroup>\n<thead>\n<tr>\n<th colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-SeqNfye4OdbguFcxxcDcQ3Jtn9c\">Item<\/div>\n<\/th>\n<th colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-Cd9xfPCKGdPSNfc81pkcaW4ZnVc\">Specification<\/div>\n<\/th>\n<th colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-EtI0fr96JdarnncyiGscvnZzn9d\">Item<\/div>\n<\/th>\n<th colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-PxLAfpX5fdFQT8c0egicWIfan7c\">Specification<\/div>\n<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-EN3ofpKJudC6FAcCWEJcUpY7nRf\">Puffs<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-FVM4fhc7Cde80ectZSZcEVOAnmf\">90000<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-DejDfjYrpdDFU5cCwcQcOpEhn5b\">Charging Type<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-MuTTfeAO4dbjHncazmhcPCPBn4e\">Type-C<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-Q7mBfxilBddyOdcgr9XcOgpGnec\">Battery Capacity<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-HA4Xf3EwhdzAygcV6kRcCaabnJP\">850mAh<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-QZzNfFewzdYuT2c0v4Acnwgknbf\">Display<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-HLnbfAfYpdhL3lcDqatc0rhfn97\">With Display<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-YtHcfFIr4dG0iGcg2qwcHb5XnQT\">E-liquid Volume<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-IbYDfVkB5d9pb0cbpMUcHCinnRf\">50ML<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-RdtBfTToJdD7PhcOOh2cMc5ynSd\">Disposable<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-FqBRfVaagdItdgcAcmSc7NK5nEe\">Disposable<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-HVqHfNl1EdKSNUcaXeScrU9RnVb\">Nicotine Content<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-GZhAfCE7RdHnY2cTI4xc7GxNnFf\">2% 5% Salt Nicotine<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-Bg6nfSH2wd1mS8cPPvhc2LLenrh\">Coil<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-P2OmfihBtdsr0GcPIOXcw2nHnve\">Mesh Coils<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-P8g8ftP26d2DMEcVPf5cvctonEb\">Packaging<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-VDXqfv7WtdbPrNcXyCSc7dwCnJd\">10pcs 1 display box<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-JdoJft92XdtyqVcUMlwc63X9nxh\">Origin<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-A5S1fPcASdyUJ2c4m8Gc7g3dndc\">China<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-ARiOfMheEdg3mlcUYnMcxOhZnAm\">Start Mode<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-QWGCfRuaUdkWFacE1IncGhUYn5b\">Sensor<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-HTfMf2Va7dWcVPc55kkcmDi6nZP\">Suitable For<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"ace-line ace-line old-record-id-PFzOfs0yXdqv4EctRPecZ2oNnoc\">ALL\u226518<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"ace-line ace-line old-record-id-YRadf4g3NdKiHDcCcchcj5brnDW\">Factory-direct wholesale, strict quality control, competitive price and reliable supply. A perfect choice for distributors and vapers pursuing convenience and high quality.<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Vhill Triple 90000 Puff 3in1 Disposable Vape is a high-capacity 90K puff rechargeable e-cigarette with 850mAh Type\u2011C battery, smart display, 50ml e\u2011liquid, mesh coil, RGB light, and 3 switchable flavors. Available Premium VHILL Triple 90K disposable vape supports 90000 puffs, equipped with smart display, RGB light and multiple nicotine strengths, perfect for global wholesale distribution.<\/p>","protected":false},"featured_media":19146,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[1131],"product_cat":[564,755,1132],"product_tag":[1137,1136,1139,624,334,230,1138,377],"class_list":["post-18954","product","type-product","status-publish","has-post-thumbnail","product_brand-hvill","product_cat-80000-puffs-disposable-vape","product_cat-eu-warehouse","product_cat-vhill","product_tag-3in1-disposable-vape","product_tag-90000-puff-disposable-vape","product_tag-90k-puff-vape","product_tag-flavor-switch-vape","product_tag-mesh-coil-vape","product_tag-rechargeable-disposable-vape","product_tag-vhill-triple-vape","product_tag-wholesale-disposable-vape","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VHILL Triple 90K Disposable Vape 90000 Puffs % Wholesale vapeuni.com -<\/title>\n<meta name=\"description\" content=\"Original China wholesale VHILL Triple 90K disposable vape with 90000 puffs, 850mAh rechargeable battery, mesh coil and rich triple fruit flavors for bulk business.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vapeuni.com\/fr\/produit\/vhill-triple-90k-disposable-vape-90000-puffs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VHILL Triple 90K Disposable Vape 90000 Puffs % Wholesale vapeuni.com -\" \/>\n<meta property=\"og:description\" content=\"Original China wholesale VHILL Triple 90K disposable vape with 90000 puffs, 850mAh rechargeable battery, mesh coil and rich triple fruit flavors for bulk business.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vapeuni.com\/fr\/produit\/vhill-triple-90k-disposable-vape-90000-puffs\/\" \/>\n<meta property=\"og:site_name\" content=\"vapeuni.com\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-22T09:12:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vapeuni.com\/wp-content\/uploads\/2026\/05\/e6b5b7e68aa51-e8b083e695b4e4b8ba-1200x1200-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vapeuni.com\\\/product\\\/vhill-triple-90k-disposable-vape-90000-puffs\\\/\",\"url\":\"https:\\\/\\\/vapeuni.com\\\/product\\\/vhill-triple-90k-disposable-vape-90000-puffs\\\/\",\"name\":\"VHILL Triple 90K Disposable Vape 90000 Puffs % Wholesale vapeuni.com -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vapeuni.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vapeuni.com\\\/product\\\/vhill-triple-90k-disposable-vape-90000-puffs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vapeuni.com\\\/product\\\/vhill-triple-90k-disposable-vape-90000-puffs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vapeuni.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/e6b5b7e68aa51-e8b083e695b4e4b8ba-1200x1200-1.webp\",\"datePublished\":\"2026-05-20T07:25:52+00:00\",\"dateModified\":\"2026-05-22T09:12:47+00:00\",\"description\":\"Original China wholesale VHILL Triple 90K disposable vape with 90000 puffs, 850mAh rechargeable battery, mesh coil and rich triple fruit flavors for bulk business.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vapeuni.com\\\/product\\\/vhill-triple-90k-disposable-vape-90000-puffs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vapeuni.com\\\/product\\\/vhill-triple-90k-disposable-vape-90000-puffs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vapeuni.com\\\/product\\\/vhill-triple-90k-disposable-vape-90000-puffs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vapeuni.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/e6b5b7e68aa51-e8b083e695b4e4b8ba-1200x1200-1.webp\",\"contentUrl\":\"https:\\\/\\\/vapeuni.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/e6b5b7e68aa51-e8b083e695b4e4b8ba-1200x1200-1.webp\",\"width\":1200,\"height\":1200,\"caption\":\"VHILL Triple 90K 3in1 vape with 90000 puffs, Mixed Berry, Triple Melon, Fizzy Cherry flavors, 850mAh, Type-C rechargeable\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vapeuni.com\\\/product\\\/vhill-triple-90k-disposable-vape-90000-puffs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vapeuni.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/vapeuni.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vhill Triple 90000 Puff 3in1 90K Disposable Vape Switch Three Flavors\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vapeuni.com\\\/#website\",\"url\":\"https:\\\/\\\/vapeuni.com\\\/\",\"name\":\"vapeuni.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vapeuni.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VHILL Triple 90K Disposable Vape 90000 Puffs % Wholesale vapeuni.com -","description":"Original China wholesale VHILL Triple 90K disposable vape with 90000 puffs, 850mAh rechargeable battery, mesh coil and rich triple fruit flavors for bulk business.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vapeuni.com\/fr\/produit\/vhill-triple-90k-disposable-vape-90000-puffs\/","og_locale":"fr_FR","og_type":"article","og_title":"VHILL Triple 90K Disposable Vape 90000 Puffs % Wholesale vapeuni.com -","og_description":"Original China wholesale VHILL Triple 90K disposable vape with 90000 puffs, 850mAh rechargeable battery, mesh coil and rich triple fruit flavors for bulk business.","og_url":"https:\/\/vapeuni.com\/fr\/produit\/vhill-triple-90k-disposable-vape-90000-puffs\/","og_site_name":"vapeuni.com","article_modified_time":"2026-05-22T09:12:47+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/vapeuni.com\/wp-content\/uploads\/2026\/05\/e6b5b7e68aa51-e8b083e695b4e4b8ba-1200x1200-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vapeuni.com\/product\/vhill-triple-90k-disposable-vape-90000-puffs\/","url":"https:\/\/vapeuni.com\/product\/vhill-triple-90k-disposable-vape-90000-puffs\/","name":"VHILL Triple 90K Disposable Vape 90000 Puffs % Wholesale vapeuni.com -","isPartOf":{"@id":"https:\/\/vapeuni.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vapeuni.com\/product\/vhill-triple-90k-disposable-vape-90000-puffs\/#primaryimage"},"image":{"@id":"https:\/\/vapeuni.com\/product\/vhill-triple-90k-disposable-vape-90000-puffs\/#primaryimage"},"thumbnailUrl":"https:\/\/vapeuni.com\/wp-content\/uploads\/2026\/05\/e6b5b7e68aa51-e8b083e695b4e4b8ba-1200x1200-1.webp","datePublished":"2026-05-20T07:25:52+00:00","dateModified":"2026-05-22T09:12:47+00:00","description":"Original China wholesale VHILL Triple 90K disposable vape with 90000 puffs, 850mAh rechargeable battery, mesh coil and rich triple fruit flavors for bulk business.","breadcrumb":{"@id":"https:\/\/vapeuni.com\/product\/vhill-triple-90k-disposable-vape-90000-puffs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vapeuni.com\/product\/vhill-triple-90k-disposable-vape-90000-puffs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vapeuni.com\/product\/vhill-triple-90k-disposable-vape-90000-puffs\/#primaryimage","url":"https:\/\/vapeuni.com\/wp-content\/uploads\/2026\/05\/e6b5b7e68aa51-e8b083e695b4e4b8ba-1200x1200-1.webp","contentUrl":"https:\/\/vapeuni.com\/wp-content\/uploads\/2026\/05\/e6b5b7e68aa51-e8b083e695b4e4b8ba-1200x1200-1.webp","width":1200,"height":1200,"caption":"VHILL Triple 90K 3in1 vape with 90000 puffs, Mixed Berry, Triple Melon, Fizzy Cherry flavors, 850mAh, Type-C rechargeable"},{"@type":"BreadcrumbList","@id":"https:\/\/vapeuni.com\/product\/vhill-triple-90k-disposable-vape-90000-puffs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vapeuni.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/vapeuni.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Vhill Triple 90000 Puff 3in1 90K Disposable Vape Switch Three Flavors"}]},{"@type":"WebSite","@id":"https:\/\/vapeuni.com\/#website","url":"https:\/\/vapeuni.com\/","name":"vapeuni.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vapeuni.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":{"30":10.36,"50":9.83,"100":8.62,"200":8.06,"400":7.89,"1000":7.36},"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":10,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_maximum_quantity":null,"tiered_pricing_quantity_step":"10","_links":{"self":[{"href":"https:\/\/vapeuni.com\/fr\/wp-json\/wp\/v2\/product\/18954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vapeuni.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vapeuni.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/vapeuni.com\/fr\/wp-json\/wp\/v2\/comments?post=18954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vapeuni.com\/fr\/wp-json\/wp\/v2\/media\/19146"}],"wp:attachment":[{"href":"https:\/\/vapeuni.com\/fr\/wp-json\/wp\/v2\/media?parent=18954"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vapeuni.com\/fr\/wp-json\/wp\/v2\/product_brand?post=18954"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vapeuni.com\/fr\/wp-json\/wp\/v2\/product_cat?post=18954"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vapeuni.com\/fr\/wp-json\/wp\/v2\/product_tag?post=18954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}